{"id":6495,"date":"2023-11-10T09:11:54","date_gmt":"2023-11-10T12:11:54","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=6495"},"modified":"2023-11-10T09:18:03","modified_gmt":"2023-11-10T12:18:03","slug":"prefeitura-de-itabirito-inicia-obra-de-contencao-no-bairro-santa-rita","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/10\/11\/2023\/geral\/prefeitura-de-itabirito-inicia-obra-de-contencao-no-bairro-santa-rita\/","title":{"rendered":"Prefeitura de Itabirito inicia obra de conten\u00e7\u00e3o no bairro Santa Rita"},"content":{"rendered":"<p>O bairro Santa Rita, em <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, enfrenta problemas causados pelas chuvas desde 2020. Um barranco amea\u00e7a a seguran\u00e7a dos moradores, que j\u00e1 viram casas serem demolidas no local. A <a href=\"\/prefeitura-de-itabirito\/\">Prefeitura de Itabirito<\/a> prometeu construir um muro de conten\u00e7\u00e3o.<\/p>\n<p>Na segunda-feira (6 de novembro de 2023), o Balan\u00e7o Geral da Record TV Minas, no quadro<strong> \u201cBairro a Bairro\u201d<\/strong>, mostrou a situa\u00e7\u00e3o do bairro e ouviu as reclama\u00e7\u00f5es dos moradores. Segundo eles, a Prefeitura colocou uma canaleta no bordo da pista para evitar que a \u00e1gua escorra, mas isso n\u00e3o resolveu o problema. Al\u00e9m disso, os moradores afirmaram que eles mesmo fizeram o esgoto e que a Prefeitura no caso, respons\u00e1vel pelo servi\u00e7o \u00e9 o <strong>Saae,<\/strong>\u00a0cobra pelo servi\u00e7o, mas n\u00e3o trata o esgoto, que \u00e9 despejado no c\u00f3rrego, no entanto, a Prefeitura n\u00e3o se pronunciou sobre o esgoto sem tratamento.<\/p>\n<p>A reportagem do <a href=\"https:\/\/noticias-gospel.org\/teste\/\">Agito Mais<\/a> entrou em contato com a Prefeitura de Itabirito para esclarecer os fatos, e por meio da Secretaria de Obras e Servi\u00e7os, informou que a obra de conten\u00e7\u00e3o na Rua Jo\u00e3o Damasceno, no bairro Santa Rita, foi iniciada nessa ter\u00e7a-feira, dia 7 de novembro. A obra consiste na constru\u00e7\u00e3o de uma estrutura de gabi\u00e3o, que \u00e9 um tipo de muro feito com pedras e arame, para conter a encosta que amea\u00e7a deslizar sobre as casas.<\/p>\n<p>A obra de conten\u00e7\u00e3o no bairro Santa Rita \u00e9 uma das v\u00e1rias interven\u00e7\u00f5es que a Prefeitura de Itabirito esta realizando desde a enchente de 2022, que causou danos em diversas \u00e1reas do munic\u00edpio, inclusive nos distritos. Segundo a Prefeitura, as obras de conten\u00e7\u00e3o t\u00eam como objetivo garantir a seguran\u00e7a e a tranquilidade da popula\u00e7\u00e3o que vive em \u00e1reas de risco.<\/p>\n","protected":false},"excerpt":{"rendered":"O bairro Santa Rita, em Itabirito, na regi\u00e3o Central de Minas Gerais, enfrenta problemas causados pelas chuvas desde 2020. Um barranco amea\u00e7a a seguran\u00e7a dos moradores, que j\u00e1 viram casas serem demolidas no local. A Prefeitura de Itabirito prometeu construir um muro de conten\u00e7\u00e3o. Na segunda-feira (6 de novembro de 2023), o Balan\u00e7o Geral da [&hellip;]","protected":false},"author":2,"featured_media":6497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,15,18,66],"class_list":["post-6495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-itabirito-mg","tag-minas-gerais","tag-prefeitura-de-itabirito"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=6495"}],"version-history":[{"count":6,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6495\/revisions"}],"predecessor-version":[{"id":6499,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6495\/revisions\/6499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/6497"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=6495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=6495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=6495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}