{"id":6781,"date":"2023-11-20T17:30:30","date_gmt":"2023-11-20T20:30:30","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=6781"},"modified":"2023-11-20T16:22:19","modified_gmt":"2023-11-20T19:22:19","slug":"vento-forte-e-mineracao-levantam-nuvem-de-poeira-na-br-356","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/20\/11\/2023\/geral\/vento-forte-e-mineracao-levantam-nuvem-de-poeira-na-br-356\/","title":{"rendered":"Vento forte e minera\u00e7\u00e3o levantam nuvem de poeira na BR-356"},"content":{"rendered":"<p>Uma grande nuvem de poeira invadiu a <a href=\"\/br356\/\">BR-356<\/a>, na altura do Alphaville, em <a href=\"\/nova-lima-mg\/\">Nova Lima<\/a>, na regi\u00e3o metropolitana de <a href=\"\/belo-horizonte-mg\/\">Belo Horizonte<\/a>, na tarde deste domingo (19 de novembro de 2023). A ventania foi registrada por motoristas que passavam pela Rodovia dos Inconfidentes, que tiveram que diminuir a velocidade e ligar o pisca alerta, devido \u00e0 dificuldade de enxergar na estrada.<\/p>\n<p>Motoristas que trafegavam no local, relataram que ficaram assustados com a situa\u00e7\u00e3o. Eles disseram que parecia que uma tempestade de areia estava se formando na regi\u00e3o com a visibilidade bem baixa, e ficaram com bastante medo de acontecer um acidente de situa\u00e7\u00e3o bem grave.<\/p>\n<p>De acordo com o Diretor de Meteorologia da Defesa Civil de BH, Dayan Carvalho, a nuvem de poeira n\u00e3o foi causada por um fen\u00f4meno espec\u00edfico, mas sim pela \u201cconsequ\u00eancia da a\u00e7\u00e3o do vento e a presen\u00e7a da minera\u00e7\u00e3o\u201d na regi\u00e3o. Ele explicou que o vento forte levantou a poeira que estava no solo, formando a nuvem.<\/p>\n<p>No mesmo dia, na parte da manh\u00e3, tamb\u00e9m em Nova Lima, houve registro de chuva forte, que pode ter contribu\u00eddo para a forma\u00e7\u00e3o do fen\u00f4meno.<\/p>\n","protected":false},"excerpt":{"rendered":"Uma grande nuvem de poeira invadiu a BR-356, na altura do Alphaville, em Nova Lima, na regi\u00e3o metropolitana de Belo Horizonte, na tarde deste domingo (19 de novembro de 2023). A ventania foi registrada por motoristas que passavam pela Rodovia dos Inconfidentes, que tiveram que diminuir a velocidade e ligar o pisca alerta, devido \u00e0 [&hellip;]","protected":false},"author":2,"featured_media":6784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[23,55,41,26],"class_list":["post-6781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-belo-horizonte-mg","tag-br356","tag-capa","tag-nova-lima-mg"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=6781"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6781\/revisions"}],"predecessor-version":[{"id":6785,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6781\/revisions\/6785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/6784"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=6781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=6781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=6781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}