{"id":6791,"date":"2023-11-21T09:46:10","date_gmt":"2023-11-21T12:46:10","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=6791"},"modified":"2023-11-21T09:46:10","modified_gmt":"2023-11-21T12:46:10","slug":"motorista-inabilitado-bate-em-poste-em-itabirito-e-sai-ileso","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/21\/11\/2023\/geral\/motorista-inabilitado-bate-em-poste-em-itabirito-e-sai-ileso\/","title":{"rendered":"Motorista inabilitado bate em poste em Itabirito e sai ileso"},"content":{"rendered":"<p>Um acidente envolvendo um Fiat Uno aconteceu na tarde desta segunda-feira (20 de novembro de 2023), no bairro Santa Tereza, em <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>. O motorista, que n\u00e3o possui carteira de habilita\u00e7\u00e3o(CNH), perdeu o controle do carro e colidiu com um poste na Rua Engenheiro Sim\u00e3o Lacerda.<\/p>\n<p>De acordo com a <a href=\"\/gcm-itabirito\/\">Guarda Civil Municipal de Itabirito<\/a>(GCMI), que atendeu a ocorr\u00eancia, o condutor n\u00e3o apresentava sinais de embriaguez e foi submetido ao teste de baf\u00f4metro, que deu negativo. Ningu\u00e9m ficou ferido no acidente.<\/p>\n<p>A GCMI informou ainda que o ve\u00edculo estava com a documenta\u00e7\u00e3o irregular, pois o \u00faltimo pagamento do IPVA foi em 2021. O carro foi removido para o P\u00e1tio credenciado e o motorista foi autuado por dirigir sem habilita\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"Um acidente envolvendo um Fiat Uno aconteceu na tarde desta segunda-feira (20 de novembro de 2023), no bairro Santa Tereza, em Itabirito, na regi\u00e3o Central de Minas Gerais. O motorista, que n\u00e3o possui carteira de habilita\u00e7\u00e3o(CNH), perdeu o controle do carro e colidiu com um poste na Rua Engenheiro Sim\u00e3o Lacerda. De acordo com a [&hellip;]","protected":false},"author":2,"featured_media":6793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,67,15,18],"class_list":["post-6791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-gcm-itabirito","tag-itabirito-mg","tag-minas-gerais"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=6791"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6791\/revisions"}],"predecessor-version":[{"id":6794,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6791\/revisions\/6794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/6793"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=6791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=6791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=6791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}