{"id":6795,"date":"2023-11-21T12:01:22","date_gmt":"2023-11-21T15:01:22","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=6795"},"modified":"2023-11-21T10:07:40","modified_gmt":"2023-11-21T13:07:40","slug":"policia-militar-prende-dupla-de-traficantes-em-amarantina","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/21\/11\/2023\/policia\/policia-militar-prende-dupla-de-traficantes-em-amarantina\/","title":{"rendered":"Pol\u00edcia Militar prende dupla de traficantes em Amarantina"},"content":{"rendered":"<div class=\"message\">\n<div class=\"content\" tabindex=\"0\">\n<div class=\"ac-container ac-adaptiveCard\">\n<div class=\"ac-textBlock\">\n<p>Uma opera\u00e7\u00e3o da <a href=\"\/policia-militar\/\">Pol\u00edcia Militar de Minas Gerais<\/a> (PMMG) resultou na pris\u00e3o de dois traficantes de drogas no distrito de <strong>Amarantina<\/strong>, em <a href=\"\/ouro-preto-mg\/\">Ouro Preto<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>. A ocorr\u00eancia foi registrada na \u00faltima sexta-feira (17 de novembro de 2023), no centro da cidade.<\/p>\n<p>Segundo a PMMG, os suspeitos s\u00e3o bem conhecidos da pol\u00edcia e foram flagrados com diversas drogas durante um patrulhamento preventivo do 3\u00ba Agrupamento. Ao verem a aproxima\u00e7\u00e3o da viatura, eles tentaram escapar, mas foram perseguidos e detidos pelos soldados Vilela e Patterson.<\/p>\n<p>Na revista, os policiais apreenderam 21 buchas de maconha, 32 pedras de crack, um simulacro de arma de fogo, tr\u00eas celulares, um carregador port\u00e1til e R$ 125,50 em dinheiro. Os materiais foram confiscados e os suspeitos foram conduzidos para a Delegacia de <a href=\"\/policia-civil\/\">Pol\u00edcia Civil<\/a> de Ouro Preto.<\/p>\n<p>A PMMG informou que a a\u00e7\u00e3o foi r\u00e1pida e eficaz e que contribuiu para a seguran\u00e7a do distrito, retirando de circula\u00e7\u00e3o uma quantidade consider\u00e1vel de drogas e prendendo os envolvidos.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Uma opera\u00e7\u00e3o da Pol\u00edcia Militar de Minas Gerais (PMMG) resultou na pris\u00e3o de dois traficantes de drogas no distrito de Amarantina, em Ouro Preto, na regi\u00e3o Central de Minas Gerais. A ocorr\u00eancia foi registrada na \u00faltima sexta-feira (17 de novembro de 2023), no centro da cidade. Segundo a PMMG, os suspeitos s\u00e3o bem conhecidos da [&hellip;]","protected":false},"author":2,"featured_media":6797,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[41,18,16,60,24],"class_list":["post-6795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-capa","tag-minas-gerais","tag-ouro-preto-mg","tag-policia-civil","tag-policia-militar"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=6795"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6795\/revisions"}],"predecessor-version":[{"id":6799,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6795\/revisions\/6799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/6797"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=6795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=6795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=6795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}