{"id":6857,"date":"2023-11-22T15:46:31","date_gmt":"2023-11-22T18:46:31","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=6857"},"modified":"2023-11-22T16:00:33","modified_gmt":"2023-11-22T19:00:33","slug":"policia-troca-tiros-com-traficantes-e-apreende-drogas-e-motos-em-itabirito","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/22\/11\/2023\/policia\/policia-troca-tiros-com-traficantes-e-apreende-drogas-e-motos-em-itabirito\/","title":{"rendered":"Pol\u00edcia troca tiros com traficantes e apreende drogas e motos em Itabirito"},"content":{"rendered":"<div class=\"message\">\n<div class=\"content\" tabindex=\"0\">\n<div class=\"ac-container ac-adaptiveCard\">\n<div class=\"ac-textBlock\">\n<p>Na manh\u00e3 desta quarta-feira (22 de novembro de 2023), uma opera\u00e7\u00e3o conjunta da <a href=\"\/policia-civil\/\">Pol\u00edcia Civil<\/a> e <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a> de <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, foi realizada no bairro Dona Luizinha, na rua Violeta, onde os policiais receberam a informa\u00e7\u00e3o de que tr\u00eas motocicletas estavam sendo usadas por criminosos envolvidos com o tr\u00e1fico de drogas e que possivelmente estavam transportando grande quantidade de entorpecentes.<\/p>\n<p>Os policiais localizaram as tr\u00eas motocicletas, al\u00e9m de um carro cinza, em reuni\u00e3o no local. Ao tentarem abordar os suspeitos, o carro e uma das motos iniciaram fuga, conseguindo escapar. As outras duas motocicletas, uma pilotada por um determinado traficante, vieram em dire\u00e7\u00e3o aos policiais, e com manobras bruscas, projetaram-se contra a viatura e os policiais, que reagiram com disparos de muni\u00e7\u00e3o n\u00e3o letal. Mesmo assim, os suspeitos conseguiram fugir, ap\u00f3s abandonarem as motocicletas.<\/p>\n<p>A a\u00e7\u00e3o foi coordenada e executada com precis\u00e3o pelas equipes policiais, que encontraram uma grande quantidade de entorpecentes e outros materiais relacionados \u00e0s atividades criminosas. Foram apreendidos um aparelho celular, quatro barras de maconha, seis tabletes de maconha, 22 pinos de coca\u00edna e impressionantes 850 comprimidos de ecstasy. Al\u00e9m disso, foram apreendidas duas motocicletas e dois capacetes.<\/p>\n<p>As equipes da Pol\u00edcia Civil e Pol\u00edcia Militar continuam as dilig\u00eancias para localizar e prender os suspeitos, que j\u00e1 foram identificados. As motocicletas abandonadas foram apreendidas e encaminhadas para o p\u00e1tio credenciado do Detran, em Itabirito.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Na manh\u00e3 desta quarta-feira (22 de novembro de 2023), uma opera\u00e7\u00e3o conjunta da Pol\u00edcia Civil e Pol\u00edcia Militar de Itabirito, na regi\u00e3o Central de Minas Gerais, foi realizada no bairro Dona Luizinha, na rua Violeta, onde os policiais receberam a informa\u00e7\u00e3o de que tr\u00eas motocicletas estavam sendo usadas por criminosos envolvidos com o tr\u00e1fico de [&hellip;]","protected":false},"author":2,"featured_media":6859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[41,15,18,60,24],"class_list":["post-6857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-capa","tag-itabirito-mg","tag-minas-gerais","tag-policia-civil","tag-policia-militar"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=6857"}],"version-history":[{"count":4,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6857\/revisions"}],"predecessor-version":[{"id":6863,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6857\/revisions\/6863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/6859"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=6857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=6857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=6857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}