{"id":6986,"date":"2023-11-28T11:40:41","date_gmt":"2023-11-28T14:40:41","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=6986"},"modified":"2023-11-28T09:26:28","modified_gmt":"2023-11-28T12:26:28","slug":"mariana-lanca-sistema-de-estacionamento-rotativo-pelo-celular","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/28\/11\/2023\/geral\/mariana-lanca-sistema-de-estacionamento-rotativo-pelo-celular\/","title":{"rendered":"Mariana lan\u00e7a sistema de estacionamento rotativo pelo celular"},"content":{"rendered":"<p>A partir de sexta-feira (1\u00ba de dezembro de 2023), os motoristas que circulam pelo Centro Hist\u00f3rico de <a href=\"\/mariana-mg\/\">Mariana<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, ter\u00e3o uma nova op\u00e7\u00e3o para estacionar seus ve\u00edculos. A <a href=\"\/prefeitura-de-mariana\/\">Prefeitura de Mariana<\/a> aderiu ao sistema <strong>Pare F\u00e1cil<\/strong>, um aplicativo que permite o cadastro de usu\u00e1rios e o pagamento de vagas de estacionamento pelo celular. O aplicativo est\u00e1 dispon\u00edvel para download na App Store e Google Play.<\/p>\n<p>O sistema prev\u00ea 349 vagas, em ruas, avenidas e no entorno de pra\u00e7as do Centro Hist\u00f3rico. As vagas s\u00e3o demarcadas por placas de sinaliza\u00e7\u00e3o, que indicam o tempo m\u00e1ximo de perman\u00eancia, que varia de 30 minutos a 2 horas. Os valores cobrados s\u00e3o de R$2 a R$4 para carros e de R$1 a R$2,50 para motos.<\/p>\n<p>Segundo o diretor de Tr\u00e2nsito de Mariana, Charles Melo, o rotativo cria um fluxo cont\u00ednuo de vagas e facilita a mobilidade e a experi\u00eancia dos motoristas:<\/p>\n<blockquote><p>\u201cEssa \u00e9 uma demanda que visa o ordenamento do tr\u00e2nsito e a comodidade ao condutor que, saindo de casa com seu carro, ter\u00e1 a certeza que encontrar\u00e1 vaga para estacionar\u201d, esclarece.<\/p><\/blockquote>\n<h4>Baixe o aplicativo <strong>PARE F\u00c1CIL<\/strong> em seu smartphone nos links que o <strong>Agito Mais<\/strong> disponibilizou abaixo:<\/h4>\n<p><strong>Para Android:<\/strong> <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=br.com.sistemaexpert.parefacil&amp;pli=1\" target=\"_blank\" rel=\"noopener\">https:\/\/play.google.com\/store\/apps\/details?id=br.com.sistemaexpert.parefacil&amp;pli=1<\/a><\/p>\n<p><strong>Para IOS:<\/strong> <a href=\"https:\/\/apps.apple.com\/br\/app\/pare-f%C3%A1cil\/id1490261253\" target=\"_blank\" rel=\"noopener\">https:\/\/apps.apple.com\/br\/app\/pare-f%C3%A1cil\/id1490261253<\/a><\/p>\n<p>O Pare F\u00e1cil \u00e9 monitorado e fiscalizado pela <a href=\"\/gcm-mariana\/\">Guarda Civil de Mariana<\/a> atrav\u00e9s de um carro OCR de videomonitoramento. O autom\u00f3vel possui quatro c\u00e2meras que captam se a placa do ve\u00edculo est\u00e1 registrada no sistema do Pare F\u00e1cil. O condutor que n\u00e3o adequar ao sistema, comete infra\u00e7\u00e3o grave e estar\u00e1 sujeito a multa de R$195,23. O ve\u00edculo ser\u00e1 levado ao p\u00e1tio credenciado.<\/p>\n","protected":false},"excerpt":{"rendered":"A partir de sexta-feira (1\u00ba de dezembro de 2023), os motoristas que circulam pelo Centro Hist\u00f3rico de Mariana, na regi\u00e3o Central de Minas Gerais, ter\u00e3o uma nova op\u00e7\u00e3o para estacionar seus ve\u00edculos. A Prefeitura de Mariana aderiu ao sistema Pare F\u00e1cil, um aplicativo que permite o cadastro de usu\u00e1rios e o pagamento de vagas de [&hellip;]","protected":false},"author":2,"featured_media":6988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,98,17,18,76],"class_list":["post-6986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-gcm-mariana","tag-mariana-mg","tag-minas-gerais","tag-prefeitura-de-mariana"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=6986"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6986\/revisions"}],"predecessor-version":[{"id":6990,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/6986\/revisions\/6990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/6988"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=6986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=6986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=6986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}