{"id":7024,"date":"2023-11-29T11:11:57","date_gmt":"2023-11-29T14:11:57","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7024"},"modified":"2023-11-29T11:55:45","modified_gmt":"2023-11-29T14:55:45","slug":"homem-e-preso-por-furto-de-celular-no-terminal-rodoviario-de-itabirito","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/29\/11\/2023\/policia\/homem-e-preso-por-furto-de-celular-no-terminal-rodoviario-de-itabirito\/","title":{"rendered":"Homem \u00e9 preso por furto de celular no terminal rodovi\u00e1rio de Itabirito"},"content":{"rendered":"<p>Um homem de 34 anos foi preso por furto de celular no terminal rodovi\u00e1rio de <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, na noite da \u00faltima sexta-feira (24 de novembro de 2023). Ele foi abordado por uma equipe da Ronda Ostensiva Municipal (<strong>ROMU<\/strong>) ap\u00f3s uma den\u00fancia de uma comerciante que reconheceu o suspeito como o autor do furto de um aparelho de um de seus clientes mais cedo.<\/p>\n<p>Os guardas municipais foram at\u00e9 o banheiro masculino do terminal, onde o suspeito estava. Com ele, foi encontrado um celular da marca Samsung. O homem n\u00e3o soube explicar a proced\u00eancia do aparelho e deu caracter\u00edsticas e um n\u00famero que n\u00e3o correspondiam ao referente do aparelho.<\/p>\n<p>A equipe de guardas municipais fez contato com a delegacia de pol\u00edcia de Itabirito e verificou que havia um registro de furto de celular nas proximidades do terminal, feito por um senhor com o nome de iniciais R.F. dos Santos. Ele havia emprestado seu celular para um indiv\u00edduo de mesmo nome que o abordado, e o mesmo evadiu do local.<\/p>\n<p>Os guardas municipais ligaram para o n\u00famero de celular registrado no boletim de ocorr\u00eancia e o telefone na posse do suspeito tocou, confirmando que o aparelho era o mesmo que fora furtado. O suspeito recebeu voz de pris\u00e3o e foi levado \u00e0 unidade de pronto atendimento, onde foi constatado seu estado f\u00edsico. Ele teve seus direitos garantidos em todo o processo e foi conduzido \u00e0 delegacia de pol\u00edcia, junto com o celular apreendido, para as provid\u00eancias cab\u00edveis.<\/p>\n","protected":false},"excerpt":{"rendered":"Um homem de 34 anos foi preso por furto de celular no terminal rodovi\u00e1rio de Itabirito, na regi\u00e3o Central de Minas Gerais, na noite da \u00faltima sexta-feira (24 de novembro de 2023). Ele foi abordado por uma equipe da Ronda Ostensiva Municipal (ROMU) ap\u00f3s uma den\u00fancia de uma comerciante que reconheceu o suspeito como o [&hellip;]","protected":false},"author":2,"featured_media":7026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[41,15,18],"class_list":["post-7024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-capa","tag-itabirito-mg","tag-minas-gerais"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7024"}],"version-history":[{"count":3,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7024\/revisions"}],"predecessor-version":[{"id":7029,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7024\/revisions\/7029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7026"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}