{"id":7158,"date":"2023-12-05T15:54:36","date_gmt":"2023-12-05T18:54:36","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7158"},"modified":"2023-12-05T15:54:36","modified_gmt":"2023-12-05T18:54:36","slug":"tiroteio-em-congonhas-deixa-um-morto-e-uma-ferida","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/05\/12\/2023\/geral\/tiroteio-em-congonhas-deixa-um-morto-e-uma-ferida\/","title":{"rendered":"Tiroteio em Congonhas deixa um morto e uma ferida"},"content":{"rendered":"<p>Uma tentativa de homic\u00eddio terminou em trag\u00e9dia em <strong>Congonhas<\/strong>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, na noite de segunda-feira (04 de dezembro de 2023). Um homem de 33 anos foi assassinado a tiros dentro de um carro no bairro Vila Andreza. Sua esposa, que estava com ele no ve\u00edculo, tamb\u00e9m foi atingida na perna, mas sobreviveu.<\/p>\n<p>Segundo a <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a>, o casal foi surpreendido por um atirador que se aproximou do carro, um gol, e disparou v\u00e1rias vezes contra o motorista. A mulher, que estava no banco do passageiro, tentou se proteger, mas foi ferida na perna esquerda.<\/p>\n<p>O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (<a href=\"\/samu\/\">SAMU<\/a>) foi acionado e chegou ao local, onde encontrou o carro atravessado na via. Os socorristas tentaram reanimar o homem, mas ele n\u00e3o resistiu aos ferimentos e morreu no local. A mulher foi encaminhada ao hospital para cuidados m\u00e9dicos.<\/p>\n<p>A <a href=\"\/policia-civil\/\">Pol\u00edcia Civil<\/a> vai investigar a motiva\u00e7\u00e3o e a autoria do crime. At\u00e9 o momento, ningu\u00e9m foi preso. A per\u00edcia recolheu c\u00e1psulas de muni\u00e7\u00e3o no local do tiroteio.<\/p>\n","protected":false},"excerpt":{"rendered":"Uma tentativa de homic\u00eddio terminou em trag\u00e9dia em Congonhas, na regi\u00e3o Central de Minas Gerais, na noite de segunda-feira (04 de dezembro de 2023). Um homem de 33 anos foi assassinado a tiros dentro de um carro no bairro Vila Andreza. Sua esposa, que estava com ele no ve\u00edculo, tamb\u00e9m foi atingida na perna, mas [&hellip;]","protected":false},"author":2,"featured_media":7160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,18,60,24,97],"class_list":["post-7158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-minas-gerais","tag-policia-civil","tag-policia-militar","tag-samu"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7158"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7158\/revisions"}],"predecessor-version":[{"id":7161,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7158\/revisions\/7161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7160"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}