{"id":7234,"date":"2023-12-09T09:10:49","date_gmt":"2023-12-09T12:10:49","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7234"},"modified":"2023-12-09T09:10:49","modified_gmt":"2023-12-09T12:10:49","slug":"menor-e-apreendido-com-dinheiro-e-caderneta-do-trafico-em-itabirito","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/09\/12\/2023\/policia\/menor-e-apreendido-com-dinheiro-e-caderneta-do-trafico-em-itabirito\/","title":{"rendered":"Menor \u00e9 apreendido com dinheiro e caderneta do tr\u00e1fico em Itabirito"},"content":{"rendered":"<p>A <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a> de <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, realizou na quinta-feira (7 de dezembro de 2023), uma opera\u00e7\u00e3o de combate e repress\u00e3o ao com\u00e9rcio il\u00edcito de drogas no bairro Padre Adelmo. Durante o patrulhamento preventivo, a equipe policial avistou o menor infrator, de 17 anos, saindo da rua Tombadouro esquina com rua Esmeril, local conhecido como ponto de venda de drogas.<\/p>\n<p>O jovem seguia a p\u00e9 em dire\u00e7\u00e3o \u00e0 rua Chancudo, mas ao perceber a presen\u00e7a policial, mudou de dire\u00e7\u00e3o e acelerou a passada. Diante da fundada suspeita, o menor foi abordado e submetido \u00e0 busca pessoal.<\/p>\n<p>Na posse do menor, foi encontrada uma bolsa lateral de cor preta, contendo quatro ma\u00e7os de notas fracionadas em diversas c\u00e9dulas de valores variados, totalizando R$ 2.657,00 (dois mil seiscentos e cinquenta e sete reais). O dinheiro estava acondicionado separadamente em compartimentos diversos na bolsa, de forma t\u00edpica para utiliza\u00e7\u00e3o no com\u00e9rcio il\u00edcito de drogas.<\/p>\n<p>Juntamente com o dinheiro, foi localizada uma caderneta de anota\u00e7\u00f5es t\u00edpicas do controle da venda il\u00edcita de drogas, com especifica\u00e7\u00f5es de g\u00edrias dadas aos entorpecentes no mundo do crime, como \u00f3leo, px, ch\u00e1, bem como especifica\u00e7\u00f5es de quantidades e nomes dos envolvidos no tr\u00e1fico, como o menor, sorvete, JJ, HDS, carrapato.<\/p>\n<p>Durante a abordagem policial, o menor informou n\u00e3o estar trabalhando atualmente e n\u00e3o soube informar a origem l\u00edcita do dinheiro. Relatou que estaria indo na mercearia a fim de adquirir um rolo de papel insulfilm, por\u00e9m o local estaria fechado.<\/p>\n<p>Diante dos elementos f\u00e1ticos de autoria e materialidade do jovem estar associado a demais pessoas para a pr\u00e1tica do crime de tr\u00e1fico de drogas, o menor e o material foram apreendidos. Feito contato com a genitora do menor, que acompanhou o registro, a m\u00e3e informou que o menor n\u00e3o est\u00e1 morando na casa dela.<\/p>\n<p>A equipe policial deslocou com os envolvidos e materiais at\u00e9 a sede da 250\u00aa Cia PM para o registro. De praxe, o menor passou por avalia\u00e7\u00e3o m\u00e9dica na Unidade de Pronto Atendimento (UPA) <span>Celso Matos da Silva de Itabirito<\/span> e em seguida foi apresentado na DP de plant\u00e3o em <a href=\"\/ouro-preto-mg\/\">Ouro Preto<\/a>, na regi\u00e3o Central do Estado, juntamente com sua genitora e os materiais apreendidos.<\/p>\n<blockquote><p>O jovem disse na presen\u00e7a de sua genitora que: \u201cEsse dinheiro n\u00e3o faz diferen\u00e7a, consigo esse valor em uma semana na biqueira.\u201d<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"A Pol\u00edcia Militar de Itabirito, na regi\u00e3o Central de Minas Gerais, realizou na quinta-feira (7 de dezembro de 2023), uma opera\u00e7\u00e3o de combate e repress\u00e3o ao com\u00e9rcio il\u00edcito de drogas no bairro Padre Adelmo. Durante o patrulhamento preventivo, a equipe policial avistou o menor infrator, de 17 anos, saindo da rua Tombadouro esquina com rua [&hellip;]","protected":false},"author":2,"featured_media":7236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[41,15,18,16,24],"class_list":["post-7234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-capa","tag-itabirito-mg","tag-minas-gerais","tag-ouro-preto-mg","tag-policia-militar"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7234"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7234\/revisions"}],"predecessor-version":[{"id":7237,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7234\/revisions\/7237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7236"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}