{"id":7246,"date":"2023-12-11T09:34:10","date_gmt":"2023-12-11T12:34:10","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7246"},"modified":"2023-12-11T09:34:10","modified_gmt":"2023-12-11T12:34:10","slug":"foragido-da-justica-do-ceara-e-preso-na-cidade-de-itabirito","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/11\/12\/2023\/policia\/foragido-da-justica-do-ceara-e-preso-na-cidade-de-itabirito\/","title":{"rendered":"Foragido da Justi\u00e7a do Cear\u00e1 \u00e9 preso na cidade de Itabirito"},"content":{"rendered":"<p>Um homem de 27 anos, que estava foragido da Justi\u00e7a do Cear\u00e1 por tr\u00e1fico de drogas, foi preso na cidade de <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, neste s\u00e1bado (9 de dezembro de 2023). A pris\u00e3o foi resultado de uma opera\u00e7\u00e3o conjunta da For\u00e7a Integrada de Combate ao Crime Organizado no Cear\u00e1 (Ficco) e da <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a> de Minas Gerais.<\/p>\n<p>Segundo a Ficco, o homem \u00e9 natural de Jaguaribara, a 261 quil\u00f4metros de Fortaleza, e integra um grupo criminoso que atua na regi\u00e3o. Ele tamb\u00e9m respondia por roubo majorado e por crime do Sistema Nacional de Armas. Os policiais cumpriram o mandado de pris\u00e3o expedido pela Vara \u00danica de Jaguaretama, no Cear\u00e1, e o conduziram \u00e0 delegacia. Ele est\u00e1 \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a e deve ser transferido para o Cear\u00e1.<\/p>\n<p>A Ficco \u00e9 uma for\u00e7a-tarefa composta por diversos \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica, que tem como objetivo combater o crime organizado no Cear\u00e1. A for\u00e7a-tarefa conta com a participa\u00e7\u00e3o da <a href=\"\/policia-federal\/\">Pol\u00edcia Federal<\/a>, da Secretaria de Seguran\u00e7a P\u00fablica e Defesa Social do Cear\u00e1, da Pol\u00edcia Militar do Cear\u00e1, da <a href=\"\/policia-civil\/\">Pol\u00edcia Civil<\/a> do Cear\u00e1, da Pol\u00edcia Rodovi\u00e1ria Federal, da Secretaria Nacional de Pol\u00edticas Penais, da Per\u00edcia Forense do Cear\u00e1 e da Secretaria de Administra\u00e7\u00e3o Penitenci\u00e1ria e Ressocializa\u00e7\u00e3o do Cear\u00e1.<\/p>\n","protected":false},"excerpt":{"rendered":"Um homem de 27 anos, que estava foragido da Justi\u00e7a do Cear\u00e1 por tr\u00e1fico de drogas, foi preso na cidade de Itabirito, na regi\u00e3o Central de Minas Gerais, neste s\u00e1bado (9 de dezembro de 2023). A pris\u00e3o foi resultado de uma opera\u00e7\u00e3o conjunta da For\u00e7a Integrada de Combate ao Crime Organizado no Cear\u00e1 (Ficco) e [&hellip;]","protected":false},"author":2,"featured_media":7248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[41,15,18,60,24,73],"class_list":["post-7246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-capa","tag-itabirito-mg","tag-minas-gerais","tag-policia-civil","tag-policia-militar","tag-policia-rodoviaria-federal"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7246"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7246\/revisions"}],"predecessor-version":[{"id":7249,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7246\/revisions\/7249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7248"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}