{"id":7358,"date":"2023-12-15T08:45:03","date_gmt":"2023-12-15T11:45:03","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7358"},"modified":"2023-12-15T08:45:03","modified_gmt":"2023-12-15T11:45:03","slug":"homem-e-morto-a-tiros-no-bairro-meu-sitio-em-itabirito","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/15\/12\/2023\/geral\/homem-e-morto-a-tiros-no-bairro-meu-sitio-em-itabirito\/","title":{"rendered":"Homem \u00e9 morto a tiros no bairro Meu S\u00edtio em Itabirito"},"content":{"rendered":"<p>Um homem identificado pelas iniciais S.O, com passagens pela pol\u00edcia por tr\u00e1fico de drogas, foi executado a tiros na noite de quinta-feira (14 de dezembro de 2023), no bairro Meu S\u00edtio, em <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>. Ele foi atingido por v\u00e1rios disparos enquanto pilotava sua moto.<\/p>\n<p>A <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a> (PM) foi acionada e encontrou o corpo do homem ca\u00eddo na entrada de um galp\u00e3o, junto com duas motos, uma delas da v\u00edtima. O local estava coberto de sangue e apresentava sinais de viol\u00eancia.<\/p>\n<p>A PM acredita que o crime tenha sido motivado por um acerto de contas entre traficantes. Segundo a pol\u00edcia, o rapaz era conhecido por atuar no bairro Santo Ant\u00f4nio e tinha envolvimento com o tr\u00e1fico de drogas.<\/p>\n<p>A \u00e1rea foi isolada pela PM para a realiza\u00e7\u00e3o da per\u00edcia t\u00e9cnica da <a href=\"\/policia-civil\/\">Pol\u00edcia Civil<\/a> (PC), que liberou o corpo para a funer\u00e1ria ap\u00f3s os procedimentos. O tenente Afr\u00e2nio, que comanda as equipes de militares, disse que as buscas pelos autores do crime continuam.<\/p>\n","protected":false},"excerpt":{"rendered":"Um homem identificado pelas iniciais S.O, com passagens pela pol\u00edcia por tr\u00e1fico de drogas, foi executado a tiros na noite de quinta-feira (14 de dezembro de 2023), no bairro Meu S\u00edtio, em Itabirito, na regi\u00e3o Central de Minas Gerais. Ele foi atingido por v\u00e1rios disparos enquanto pilotava sua moto. A Pol\u00edcia Militar (PM) foi acionada [&hellip;]","protected":false},"author":2,"featured_media":7360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,15,18,60,24],"class_list":["post-7358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-itabirito-mg","tag-minas-gerais","tag-policia-civil","tag-policia-militar"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7358"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7358\/revisions"}],"predecessor-version":[{"id":7361,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7358\/revisions\/7361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7360"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}