{"id":7368,"date":"2023-12-15T10:17:42","date_gmt":"2023-12-15T13:17:42","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7368"},"modified":"2023-12-15T10:17:42","modified_gmt":"2023-12-15T13:17:42","slug":"justica-suspende-direitos-politicos-de-prefeito-de-ouro-preto-por-cinco-anos","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/15\/12\/2023\/geral\/justica-suspende-direitos-politicos-de-prefeito-de-ouro-preto-por-cinco-anos\/","title":{"rendered":"Justi\u00e7a suspende direitos pol\u00edticos de prefeito de Ouro Preto por cinco anos"},"content":{"rendered":"<p>O prefeito de <a href=\"\/ouro-preto-mg\/\">Ouro Preto<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, Angelo Oswaldo, teve seus direitos pol\u00edticos suspensos por cinco anos pela 2\u00aa C\u00e2mara C\u00edvel do Tribunal de Justi\u00e7a de Minas Gerais, por improbidade administrativa. A decis\u00e3o, que cabe recurso, foi proferida nessa ter\u00e7a-feira (12 de\u00a0 dezembro de 2023) e se refere a um caso que aconteceu na gest\u00e3o dele entre 1993 e 1996, quando ele assumiu o primeiro mandato na cidade hist\u00f3rica.<\/p>\n<p>Segundo o processo, Angelo Oswaldo \u00e9 acusado de pagar por uma obra de cal\u00e7amento no distrito de Santo Ant\u00f4nio do Salto, que n\u00e3o foi conclu\u00edda, mas os valores foram repassados \u00e0s empresas respons\u00e1veis. O munic\u00edpio ficou inadimplente quanto \u00e0 presta\u00e7\u00e3o de contas do conv\u00eanio com o Estado de Minas Gerais, o que motivou a investiga\u00e7\u00e3o do Minist\u00e9rio P\u00fablico de Minas Gerais (MPMG), que substituiu a 1\u00aa Vara C\u00edvel da Comarca de Ouro Preto na a\u00e7\u00e3o.<\/p>\n<p>O Ac\u00f3rd\u00e3o, assinado pelo Desembargador Marcelo Rodrigues, rejeitou a alega\u00e7\u00e3o da defesa de Angelo Oswaldo de cerceamento de defesa pela demora no julgamento, que j\u00e1 dura 26 anos. O documento afirmou que os requeridos usaram de recursos para retardar o tr\u00e2mite do feito e que h\u00e1 provas de que a obra n\u00e3o foi conclu\u00edda e que o ent\u00e3o Secret\u00e1rio de Obras, S\u00e9rgio Barbosa Queiroz, atestou a conclus\u00e3o sem ir ao local. O Ac\u00f3rd\u00e3o tamb\u00e9m determinou que o valor do dano seja corrigido e ressarcido aos cofres p\u00fablicos.<\/p>\n<p>Segundo o jornal Estado de Minas, o prefeito de Ouro Preto, Angelo Oswaldo, disse que vai recorrer da decis\u00e3o ap\u00f3s a publica\u00e7\u00e3o do ac\u00f3rd\u00e3o. Ele afirmou que tem a possibilidade de entrar com embargo e que espera que o caso seja reformado no tribunal ou no Supremo Tribunal Federal (STF). Ele alegou que o processo foi montado para prejudic\u00e1-lo e torn\u00e1-lo ineleg\u00edvel e que a justi\u00e7a pode ter dificuldade de compreender os equ\u00edvocos na acusa\u00e7\u00e3o. Ele destacou os 50 anos de vida p\u00fablica e disse que foi eleito tr\u00eas vezes prefeito da cidade ap\u00f3s a a\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n","protected":false},"excerpt":{"rendered":"O prefeito de Ouro Preto, na regi\u00e3o Central de Minas Gerais, Angelo Oswaldo, teve seus direitos pol\u00edticos suspensos por cinco anos pela 2\u00aa C\u00e2mara C\u00edvel do Tribunal de Justi\u00e7a de Minas Gerais, por improbidade administrativa. A decis\u00e3o, que cabe recurso, foi proferida nessa ter\u00e7a-feira (12 de\u00a0 dezembro de 2023) e se refere a um caso [&hellip;]","protected":false},"author":2,"featured_media":7370,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,18,16],"class_list":["post-7368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-minas-gerais","tag-ouro-preto-mg"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7368"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7368\/revisions"}],"predecessor-version":[{"id":7371,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7368\/revisions\/7371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7370"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}