{"id":7444,"date":"2023-12-19T12:41:36","date_gmt":"2023-12-19T15:41:36","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7444"},"modified":"2023-12-19T13:00:29","modified_gmt":"2023-12-19T16:00:29","slug":"alerta-chuva-pode-chegar-a-itabirito-apos-alguns-dias-de-muito-calor","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/19\/12\/2023\/geral\/alerta-chuva-pode-chegar-a-itabirito-apos-alguns-dias-de-muito-calor\/","title":{"rendered":"Alerta: chuva pode chegar a Itabirito ap\u00f3s alguns dias de muito calor"},"content":{"rendered":"<p>Ap\u00f3s v\u00e1rios dias sem chuva e de muito calor, a cidade de <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, pode receber nesta ter\u00e7a-feira (19 de dezembro de 2023), precipita\u00e7\u00f5es de 10 a 30 mm nas pr\u00f3ximas 24 horas, segundo o Instituto Nacional de Meteorologia (Inmet). A previs\u00e3o \u00e9 de que ocorram pancadas de chuva forte no decorrer do dia, principalmente \u00e0 tarde e \u00e0 noite.<\/p>\n<p>A chuva \u00e9 bem-vinda para aliviar o calor e a baixa umidade do ar, que chegou a 25% na segunda-feira(18). No entanto, os moradores devem ficar atentos aos poss\u00edveis transtornos causados pela chuva intensa, como alagamentos, deslizamentos e quedas de \u00e1rvores.<\/p>\n<p>O Rio Itabirito, que corta a cidade, est\u00e1 em seu n\u00edvel normal, de acordo com a <a href=\"\/defesa-civil\/\">Defesa Civil<\/a>. O \u00f3rg\u00e3o monitora o rio e alerta para a possibilidade de eleva\u00e7\u00e3o do n\u00edvel em caso de chuva forte. A recomenda\u00e7\u00e3o \u00e9 que as pessoas evitem \u00e1reas de risco e acionem a Defesa Civil em caso de emerg\u00eancia. O telefone \u00e9 o <strong>199<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Ap\u00f3s v\u00e1rios dias sem chuva e de muito calor, a cidade de Itabirito, na regi\u00e3o Central de Minas Gerais, pode receber nesta ter\u00e7a-feira (19 de dezembro de 2023), precipita\u00e7\u00f5es de 10 a 30 mm nas pr\u00f3ximas 24 horas, segundo o Instituto Nacional de Meteorologia (Inmet). A previs\u00e3o \u00e9 de que ocorram pancadas de chuva forte [&hellip;]","protected":false},"author":2,"featured_media":7446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,100,15,18],"class_list":["post-7444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-defesa-civil","tag-itabirito-mg","tag-minas-gerais"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7444"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7444\/revisions"}],"predecessor-version":[{"id":7450,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7444\/revisions\/7450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7446"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}