{"id":7650,"date":"2023-12-23T19:37:31","date_gmt":"2023-12-23T22:37:31","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7650"},"modified":"2023-12-24T08:51:19","modified_gmt":"2023-12-24T11:51:19","slug":"caminhoneiro-e-preso-por-furtar-carga-de-carreta-acidentada-na-br-381","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/23\/12\/2023\/geral\/caminhoneiro-e-preso-por-furtar-carga-de-carreta-acidentada-na-br-381\/","title":{"rendered":"Caminhoneiro \u00e9 preso por furtar carga de carreta acidentada na BR-381"},"content":{"rendered":"<p>Um caminhoneiro de 40 anos foi preso pela <a href=\"\/policia-rodoviaria-federal\/\">Pol\u00edcia Rodovi\u00e1ria Federal<\/a> (PRF) nesta sexta-feira (22 de dezembro de 2023), por furtar parte da carga de uma carreta que se envolveu em um acidente na <a href=\"\/br381\/\">BR-381<\/a>, no munic\u00edpio de Lavras, <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>. O furto (saque da carga) aconteceu no Km 703 da rodovia, onde uma carreta carregada de perfis met\u00e1licos tombou e espalhou a mercadoria pela pista.<\/p>\n<p>Os policiais rodovi\u00e1rios chegaram ao local do acidente para prestar socorro e se depararam com uma outra carreta estacionada pr\u00f3xima ao local. Ao averiguarem a situa\u00e7\u00e3o, eles constataram que o motorista da segunda carreta estava aproveitando a oportunidade para furtar os perfis met\u00e1licos do ve\u00edculo acidentado e coloc\u00e1-los em sua carroceria.<\/p>\n<p>Diante do flagrante, os policiais deram voz de pris\u00e3o ao caminhoneiro e o conduziram para a Pol\u00edcia Judici\u00e1ria em Lavras (MG), onde ele foi autuado pelo crime de furto, previsto no art. 155 do C\u00f3digo Penal Brasileiro. A carreta e a carga furtada foram apreendidas e levadas para o p\u00e1tio da PRF, onde ficaram \u00e0 disposi\u00e7\u00e3o da justi\u00e7a.<\/p>\n<p>A PRF informou que o saque de carga \u00e9 uma pr\u00e1tica criminosa que coloca em risco a seguran\u00e7a dos usu\u00e1rios da rodovia e prejudica os transportadores de mercadorias. A PRF disse ainda que tem intensificado as a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e repress\u00e3o ao saque de carga nas rodovias federais, e pediu a colabora\u00e7\u00e3o da popula\u00e7\u00e3o para denunciar esse tipo de crime.<\/p>\n","protected":false},"excerpt":{"rendered":"Um caminhoneiro de 40 anos foi preso pela Pol\u00edcia Rodovi\u00e1ria Federal (PRF) nesta sexta-feira (22 de dezembro de 2023), por furtar parte da carga de uma carreta que se envolveu em um acidente na BR-381, no munic\u00edpio de Lavras, Minas Gerais. O furto (saque da carga) aconteceu no Km 703 da rodovia, onde uma carreta [&hellip;]","protected":false},"author":2,"featured_media":7652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[104,41,18,73],"class_list":["post-7650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-br381","tag-capa","tag-minas-gerais","tag-policia-rodoviaria-federal"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7650"}],"version-history":[{"count":1,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7650\/revisions"}],"predecessor-version":[{"id":7653,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7650\/revisions\/7653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7652"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}