{"id":7680,"date":"2023-12-24T09:04:45","date_gmt":"2023-12-24T12:04:45","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7680"},"modified":"2023-12-24T09:23:40","modified_gmt":"2023-12-24T12:23:40","slug":"lotofacil-sortudo-fez-aposta-de-r-3-reais-e-levou-quase-r-4-milhoes","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/24\/12\/2023\/geral\/lotofacil-sortudo-fez-aposta-de-r-3-reais-e-levou-quase-r-4-milhoes\/","title":{"rendered":"Lotof\u00e1cil: sortudo fez aposta de R$ 3 reais e levou quase R$ 4 milh\u00f5es"},"content":{"rendered":"<p>Um apostador de Porto Velho, capital de Rond\u00f4nia, teve um Natal antecipado ao ganhar sozinho o pr\u00eamio de R$ 3.785.291,04 na Lotof\u00e1cil. Ele fez uma aposta simples de R$ 3 e acertou as 15 dezenas do concurso 2987, realizado na noite de s\u00e1bado (23 de dezembro de 2023), no Espa\u00e7o da Sorte, em S\u00e3o Paulo.<\/p>\n<p>As dezenas sorteadas foram: <strong>01, 03, 04, 06, 07, 08, 11, 12, 13, 14, 15, 16, 17, 18 e 20<\/strong>. Al\u00e9m do sortudo de Porto Velho, outras 297 apostas acertaram 14 dezenas e levaram R$ 1.702,36 cada. Outros pr\u00eamios menores foram distribu\u00eddos para quem acertou 13, 12 ou 11 dezenas.<\/p>\n<div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"notic-1547908805\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3846663955933450\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3846663955933450\" \ndata-ad-slot=\"7735491960\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>A Lotof\u00e1cil \u00e9 uma das loterias mais populares do <a href=\"\/brasil\/\">Brasil<\/a>, pois tem uma alta probabilidade de ganhar. A aposta simples custa R$ 3 e permite marcar 15 n\u00fameros entre os 25 dispon\u00edveis no volante. Quem acerta 11, 12, 13, 14 ou 15 dezenas ganha algum pr\u00eamio. A chance de acertar as 15 dezenas com uma aposta simples \u00e9 de uma em 3,2 milh\u00f5es. Mas \u00e9 poss\u00edvel aumentar as chances jogando com mais n\u00fameros, at\u00e9 o limite de 20, que custa R$ 46.512.<\/p>\n<p>Para quem gosta de arriscar, h\u00e1 ainda as op\u00e7\u00f5es da Surpresinha, que deixa o sistema escolher os n\u00fameros, e da Teimosinha, que permite concorrer com a mesma aposta por 3, 6, 12, 18 ou 24 concursos consecutivos.<\/p>\n<p>O pr\u00f3ximo sorteio da Lotof\u00e1cil ser\u00e1 na ter\u00e7a-feira (26 de dezembro de 2023), pois na segunda-feira (25) \u00e9 feriado de Natal. O pr\u00eamio estimado \u00e9 de R$ 1,7 milh\u00e3o. Quem sabe voc\u00ea n\u00e3o \u00e9 o pr\u00f3ximo sortudo? Boa sorte!<\/p>\n","protected":false},"excerpt":{"rendered":"Um apostador de Porto Velho, capital de Rond\u00f4nia, teve um Natal antecipado ao ganhar sozinho o pr\u00eamio de R$ 3.785.291,04 na Lotof\u00e1cil. Ele fez uma aposta simples de R$ 3 e acertou as 15 dezenas do concurso 2987, realizado na noite de s\u00e1bado (23 de dezembro de 2023), no Espa\u00e7o da Sorte, em S\u00e3o Paulo. [&hellip;]","protected":false},"author":2,"featured_media":7682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[68,41],"class_list":["post-7680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-brasil","tag-capa"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7680"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7680\/revisions"}],"predecessor-version":[{"id":7690,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7680\/revisions\/7690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7682"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}