{"id":7730,"date":"2023-12-25T13:30:32","date_gmt":"2023-12-25T16:30:32","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7730"},"modified":"2023-12-25T14:16:12","modified_gmt":"2023-12-25T17:16:12","slug":"motos-barulhentas-perturbam-moradores-de-itabirito-no-feriado-de-natal","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/25\/12\/2023\/geral\/motos-barulhentas-perturbam-moradores-de-itabirito-no-feriado-de-natal\/","title":{"rendered":"Motos barulhentas perturbam moradores de Itabirito no feriado de Natal"},"content":{"rendered":"<p>Os moradores de <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, n\u00e3o tiveram sossego no feriado desta segunda-feira (25 de dezembro de 2023). O <a href=\"https:\/\/noticias-gospel.org\/teste\/\">Agito Mais<\/a> foi procurado por v\u00e1rias pessoas que reclamaram do barulho das motos com escapamentos adulterados ou sem silenciador, maior parte das den\u00fancias s\u00e3o do bairro Agostinho Rodrigues. Segundo eles, o ru\u00eddo \u00e9 t\u00e3o alto que impede a comunica\u00e7\u00e3o dentro de casa e causa sofrimento aos acamados.<\/p>\n<p>Uma moradora, que n\u00e3o quis se identificar, disse ao <strong>Agito Mais<\/strong> que j\u00e1 ligou para a <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a>, mas n\u00e3o obteve solu\u00e7\u00e3o at\u00e9 o fechamento desta reportagem. Ela afirmou que a corpora\u00e7\u00e3o informou que j\u00e1 recebeu v\u00e1rias den\u00fancias sobre o caso, mas n\u00e3o esclareceu o que est\u00e1 sendo feito. A reportagem tamb\u00e9m tentou contato com a Sala de Imprensa da PM, mas n\u00e3o teve retorno.<\/p>\n<div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"notic-1574337907\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3846663955933450\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3846663955933450\" \ndata-ad-slot=\"7735491960\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>O C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB) prev\u00ea que conduzir ve\u00edculo com o escapamento ou outra caracter\u00edstica alterada \u00e9 infra\u00e7\u00e3o grave. A multa \u00e9 de R$ 195,23, mais cinco pontos na carteira, e o ve\u00edculo fica retido at\u00e9 a regulariza\u00e7\u00e3o. A mesma puni\u00e7\u00e3o se aplica a quem conduzir ve\u00edculo com descarga livre ou com o silenciador do motor estragado ou em desuso.<\/p>\n<p>Para medir o n\u00edvel de ru\u00eddo, o agente policial precisa usar um aparelho chamado decibel\u00edmetro. O Conselho Nacional do Meio Ambiente (CONAMA) estabelece os limites de ru\u00eddos nas proximidades do escapamento para ve\u00edculos automotores. Para motos fabricadas at\u00e9 1998, o limite \u00e9 de 99 decib\u00e9is (db). Para as fabricadas a partir de 1999, o limite varia entre 75 e 80 db, conforme a cilindrada.<\/p>\n<p>Al\u00e9m de ilegal, o barulho das motos prejudica a sa\u00fade auditiva das pessoas e do pr\u00f3prio condutor, bem como o meio ambiente, pois aumenta a emiss\u00e3o de fuma\u00e7a. Tamb\u00e9m desrespeita o bem-estar comum de todos, tirando a paz e a tranquilidade da sociedade.<\/p>\n<p>Antes de modificar o escapamento da sua moto, pense nas consequ\u00eancias legais e morais que pode enfrentar, al\u00e9m de poder ser preso e responder por crime ambiental, dependendo do caso.<\/p>\n","protected":false},"excerpt":{"rendered":"Os moradores de Itabirito, na regi\u00e3o Central de Minas Gerais, n\u00e3o tiveram sossego no feriado desta segunda-feira (25 de dezembro de 2023). O Agito Mais foi procurado por v\u00e1rias pessoas que reclamaram do barulho das motos com escapamentos adulterados ou sem silenciador, maior parte das den\u00fancias s\u00e3o do bairro Agostinho Rodrigues. Segundo eles, o ru\u00eddo [&hellip;]","protected":false},"author":2,"featured_media":7733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[41,15,18,24],"class_list":["post-7730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-capa","tag-itabirito-mg","tag-minas-gerais","tag-policia-militar"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7730"}],"version-history":[{"count":3,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7730\/revisions"}],"predecessor-version":[{"id":7736,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7730\/revisions\/7736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7733"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}