{"id":7857,"date":"2023-12-27T12:49:03","date_gmt":"2023-12-27T15:49:03","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7857"},"modified":"2023-12-27T12:53:42","modified_gmt":"2023-12-27T15:53:42","slug":"grave-acidente-entre-onibus-e-caminhao-fecha-br-040","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/27\/12\/2023\/geral\/grave-acidente-entre-onibus-e-caminhao-fecha-br-040\/","title":{"rendered":"Grave acidente entre \u00f4nibus e caminh\u00e3o fecha BR-040"},"content":{"rendered":"<p>Um grave acidente envolvendo um \u00f4nibus de turismo, que partiu de <a href=\"\/belo-horizonte\/\">Belo Horizonte<\/a>, na capital de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>, e um caminh\u00e3o carregado de milho interditou a <a href=\"\/br040\/\">BR-040<\/a>, na altura do km 87, na Serra de Petr\u00f3polis, na manh\u00e3 desta quarta-feira (27 de dezembro de 2023). A colis\u00e3o ocorreu por volta das 6h, a dois quil\u00f4metros do T\u00fanel do Ouri\u00e7o, no sentido Rio de Janeiro.<\/p>\n<p>Segundo a Concer, concession\u00e1ria que administra a rodovia, os dois ve\u00edculos ocuparam as duas faixas da pista de descida, impedindo o tr\u00e1fego de ve\u00edculos. A carga de milho se espalhou pela via, dificultando a remo\u00e7\u00e3o dos ve\u00edculos. Nenhum deles chegou a tombar.<\/p>\n<div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"notic-4055103262\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3846663955933450\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3846663955933450\" \ndata-ad-slot=\"7735491960\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>As equipes de resgate da Concer e do <a href=\"\/cbmg\/\">Corpo de Bombeiros<\/a> foram acionadas para socorrer as v\u00edtimas. O motorista do \u00f4nibus ficou preso \u00e0s ferragens e precisou ser retirado com o aux\u00edlio de um desencarcerador. Ele e outro passageiro sofreram ferimentos moderados e foram encaminhados para o Hospital Estadual Ad\u00e3o Pereira Nunes, em Caxias.<\/p>\n<p>Por volta das 7h30, uma faixa da pista de descida foi liberada, mas ainda havia 6 km de congestionamento no local. A Concer orienta os motoristas a terem cautela e paci\u00eancia ao passarem pelo trecho. A causa do acidente ainda \u00e9 desconhecida.<\/p>\n","protected":false},"excerpt":{"rendered":"Um grave acidente envolvendo um \u00f4nibus de turismo, que partiu de Belo Horizonte, na capital de Minas Gerais, e um caminh\u00e3o carregado de milho interditou a BR-040, na altura do km 87, na Serra de Petr\u00f3polis, na manh\u00e3 desta quarta-feira (27 de dezembro de 2023). A colis\u00e3o ocorreu por volta das 6h, a dois quil\u00f4metros [&hellip;]","protected":false},"author":2,"featured_media":7859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[23,64,41,85,18],"class_list":["post-7857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-belo-horizonte-mg","tag-br040","tag-capa","tag-cbmg","tag-minas-gerais"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7857"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7857\/revisions"}],"predecessor-version":[{"id":7861,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7857\/revisions\/7861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7859"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}