{"id":7875,"date":"2023-12-27T20:36:22","date_gmt":"2023-12-27T23:36:22","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7875"},"modified":"2023-12-27T20:44:55","modified_gmt":"2023-12-27T23:44:55","slug":"jovem-e-preso-pela-romu-apos-furtar-roupas-em-loja-de-itabirito","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/27\/12\/2023\/policia\/jovem-e-preso-pela-romu-apos-furtar-roupas-em-loja-de-itabirito\/","title":{"rendered":"Jovem \u00e9 preso pela ROMU ap\u00f3s furtar roupas em loja de Itabirito"},"content":{"rendered":"<p>A equipe da ROMU (Ronda Ostensiva Municipal) prendeu na tarde desta quarta-feira (27 de dezembro de 2023) um jovem acusado de furtar roupas de uma loja no bairro Praia, em <a href=\"\/itabirito-mg\/\">Itabirito<\/a>, na regi\u00e3o Central de <a href=\"\/minas-gerais\/\">Minas Gerais<\/a>.<\/p>\n<p>Segundo a ROMU, a pris\u00e3o ocorreu ap\u00f3s uma den\u00fancia da funcion\u00e1ria da loja, que relatou que o suspeito havia levado quatro shorts femininos que estavam expostos na porta da loja. A funcion\u00e1ria informou as caracter\u00edsticas do suspeito e a ROMU iniciou o rastreamento.<\/p>\n\n<p>O suspeito foi localizado no acesso dois da cidade, com uma sacola contendo as roupas furtadas da loja, avaliadas em cerca de R$ 150,00, e outras pe\u00e7as de proced\u00eancia duvidosa, como duas camisas masculinas, uma blusa de frio masculina, uma jaqueta feminina, uma mochila e uma bolsa.<\/p>\n<p>Ao ser abordado pela ROMU, o suspeito confessou o furto e alegou que as demais roupas eram dele. Ele recebeu voz de pris\u00e3o e foi encaminhado \u00e0 Unidade de Pronto Atendimento (UPA) Celso Matos Silva na mesma cidade, para exame de corpo de delito.<\/p>\n<p>O suspeito ser\u00e1 apresentado \u00e0 autoridade policial para as provid\u00eancias cab\u00edveis. A loja recuperou as roupas furtadas e agradeceu o trabalho da ROMU.<\/p>\n","protected":false},"excerpt":{"rendered":"A equipe da ROMU (Ronda Ostensiva Municipal) prendeu na tarde desta quarta-feira (27 de dezembro de 2023) um jovem acusado de furtar roupas de uma loja no bairro Praia, em Itabirito, na regi\u00e3o Central de Minas Gerais. Segundo a ROMU, a pris\u00e3o ocorreu ap\u00f3s uma den\u00fancia da funcion\u00e1ria da loja, que relatou que o suspeito [&hellip;]","protected":false},"author":2,"featured_media":7877,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[41,15,18],"class_list":["post-7875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-capa","tag-itabirito-mg","tag-minas-gerais"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7875"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7875\/revisions"}],"predecessor-version":[{"id":7879,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7875\/revisions\/7879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7877"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}