{"id":7890,"date":"2023-12-28T14:37:51","date_gmt":"2023-12-28T17:37:51","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=7890"},"modified":"2023-12-28T14:47:57","modified_gmt":"2023-12-28T17:47:57","slug":"termina-hoje-exame-toxicologico-obrigatorio-para-motoristas-de-veiculos-pesados","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/28\/12\/2023\/geral\/termina-hoje-exame-toxicologico-obrigatorio-para-motoristas-de-veiculos-pesados\/","title":{"rendered":"Termina hoje exame toxicol\u00f3gico obrigat\u00f3rio para motoristas de ve\u00edculos pesados"},"content":{"rendered":"<p><a href=\"\/brasil\/\">Brasil<\/a> = O Contran (Conselho Nacional de Tr\u00e2nsito) determinou, por meio da Resolu\u00e7\u00e3o n\u00ba 1.002, de 20 de outubro de 2023, que os motoristas com habilita\u00e7\u00e3o nas categorias C, D e E, que dirigem caminh\u00f5es, \u00f4nibus e vans, devem realizar o exame toxicol\u00f3gico at\u00e9 hoje, quinta-feira (28 de dezembro de 2023). O teste pode detectar o uso de subst\u00e2ncias psicoativas, que podem afetar a capacidade de conduzir e aumentar o risco de acidentes no tr\u00e2nsito.<\/p>\n<p>O exame tamb\u00e9m tem o objetivo de verificar se o condutor faz uso regular de subst\u00e2ncias proibidas.<\/p>\n<h4><strong>Como \u00e9 feito o exame<\/strong><\/h4>\n<p>O exame toxicol\u00f3gico usa amostras de cabelo e pelo do corpo do motorista. Em casos de alopecia universal (perda de cabelo e pelos corporais), comprovada por laudo m\u00e9dico de dermatologista, o exame pode ser feito pela unha.<\/p>\n<div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"notic-527135523\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3846663955933450\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3846663955933450\" \ndata-ad-slot=\"7735491960\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>O exame analisa o consumo, ativo ou n\u00e3o, de subst\u00e2ncias psicoativas nos \u00faltimos 90 dias anteriores ao teste. Os resultados s\u00e3o divulgados em at\u00e9 15 dias.<\/p>\n<p>Os motoristas devem fazer o exame em uma das 17 redes de laborat\u00f3rios credenciadas pela Senatran (Secretaria Nacional de Tr\u00e2nsito). O valor m\u00e9dio do exame \u00e9 de R$ 120. As empresas que contratam motoristas, transportadoras ou n\u00e3o, devem pagar o exame toxicol\u00f3gico para seus empregados e inserir os dados do exame no Caged (Cadastro Geral de Empregados e Desempregados). Os condutores aut\u00f4nomos devem pagar o exame por conta pr\u00f3pria.<\/p>\n<p>Os motoristas das categorias C, D e E devem renovar o exame toxicol\u00f3gico a cada 30 meses.<\/p>\n<h4><strong>Quais s\u00e3o as penalidades <\/strong><\/h4>\n<p>A partir de 28 de janeiro de 2024, os motoristas que forem flagrados dirigindo ve\u00edculo de uma das tr\u00eas categorias sem o exame toxicol\u00f3gico ou com o exame vencido h\u00e1 mais de 30 dias ser\u00e3o multados, conforme o C\u00f3digo de Tr\u00e2nsito Brasileiro. A infra\u00e7\u00e3o \u00e9 grav\u00edssima e o motorista de ve\u00edculos como \u00f4nibus e caminh\u00f5es recebe sete pontos na CNH (Carteira Nacional de Habilita\u00e7\u00e3o) e \u00e9 multado em R$ 1.467.<\/p>\n<div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"notic-625098206\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3846663955933450\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3846663955933450\" \ndata-ad-slot=\"7735491960\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Se o motorista for flagrado novamente com o exame toxicol\u00f3gico vencido, no per\u00edodo de 1 ano, a multa aumenta para R$ 2.934,70. E o motorista tem o direito de dirigir suspenso por 3 meses.<\/p>\n<p>O exame toxicol\u00f3gico \u00e9 obrigat\u00f3rio e n\u00e3o h\u00e1 como fugir dele. Mesmo que o motorista n\u00e3o seja abordado dirigindo, ele ser\u00e1 notificado em R$1.467 pelo Detran do seu estado quando for renovar a sua CNH.<\/p>\n<p>Se o resultado do exame for positivo, confirmando o uso de alguma subst\u00e2ncia proibida, o condutor tamb\u00e9m ser\u00e1 autuado e multado em R$ 1.467,35 e perder\u00e1 sete pontos na CNH.<\/p>\n<h4><strong>Como consultar o exame toxicol\u00f3gico<\/strong><\/h4>\n<p>O motorista pode consultar a validade do exame toxicol\u00f3gico na CNH digital, que tem a informa\u00e7\u00e3o sobre o exame. Se o motorista renovou a sua CNH h\u00e1 mais de 2 anos e meio, o exame est\u00e1 vencido.<\/p>\n<p>H\u00e1 1 m\u00eas, a Senatran tem enviado alertas para os celulares dos motoristas, por meio do aplicativo da Carteira Digital de Tr\u00e2nsito (CDT), para os condutores que ainda n\u00e3o fizeram o exame toxicol\u00f3gico ou est\u00e3o com o teste vencido.<\/p>\n<p>Os alertas s\u00e3o enviados de tr\u00eas formas diferentes: por notifica\u00e7\u00e3o do tipo push, com uma mensagem de alerta na tela inicial do celular, para os condutores que precisam renovar o exame; pela central de mensagens da Carteira Digital de Tr\u00e2nsito (sininho), que oferece todas as atualiza\u00e7\u00f5es para o condutor; pela \u00e1rea espec\u00edfica do exame toxicol\u00f3gico na CDT, que mostra a data da \u00faltima coleta e a necessidade de renovar o procedimento.<\/p>\n","protected":false},"excerpt":{"rendered":"Brasil = O Contran (Conselho Nacional de Tr\u00e2nsito) determinou, por meio da Resolu\u00e7\u00e3o n\u00ba 1.002, de 20 de outubro de 2023, que os motoristas com habilita\u00e7\u00e3o nas categorias C, D e E, que dirigem caminh\u00f5es, \u00f4nibus e vans, devem realizar o exame toxicol\u00f3gico at\u00e9 hoje, quinta-feira (28 de dezembro de 2023). O teste pode detectar [&hellip;]","protected":false},"author":2,"featured_media":7892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[68,41],"class_list":["post-7890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-brasil","tag-capa"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=7890"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7890\/revisions"}],"predecessor-version":[{"id":7896,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/7890\/revisions\/7896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/7892"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=7890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=7890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=7890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}