{"id":8210,"date":"2024-01-13T15:52:54","date_gmt":"2024-01-13T18:52:54","guid":{"rendered":"https:\/\/noticias-gospel.org\/teste\/?p=8210"},"modified":"2024-01-14T10:31:03","modified_gmt":"2024-01-14T13:31:03","slug":"policia-militar-frustra-roubo-e-evita-linchamento-de-criminoso-em-contagem","status":"publish","type":"post","link":"https:\/\/noticias-gospel.org\/teste\/13\/01\/2024\/policia\/policia-militar-frustra-roubo-e-evita-linchamento-de-criminoso-em-contagem\/","title":{"rendered":"Pol\u00edcia Militar frustra roubo e evita linchamento de criminoso em Contagem"},"content":{"rendered":"<p>Uma a\u00e7\u00e3o r\u00e1pida da <a href=\"\/policia-militar\/\">Pol\u00edcia Militar<\/a> impediu um assalto na Feira do Eldorado, em Contagem, na Regi\u00e3o Metropolitana de <a href=\"\/belo-horizonte-mg\/\">Belo Horizonte<\/a>, na tarde desta sexta-feira (12 de janeiro de 2024). Dois homens armados tentaram roubar os comerciantes da feira, mas foram surpreendidos por uma viatura que fazia patrulhamento no bairro.<\/p>\n<div style=\"margin-left: auto;margin-right: auto;text-align: center;\" id=\"notic-694216653\"><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-3846663955933450\" crossorigin=\"anonymous\"><\/script><ins class=\"adsbygoogle\" style=\"display:block;\" data-ad-client=\"ca-pub-3846663955933450\" \ndata-ad-slot=\"7735491960\" \ndata-ad-format=\"auto\"><\/ins>\n<script> \n(adsbygoogle = window.adsbygoogle || []).push({}); \n<\/script>\n<\/div>\n<p>Um dos assaltantes reagiu \u00e0 abordagem policial e atirou contra os militares. Houve troca de tiros e o criminoso foi baleado e morreu no local. O outro assaltante tentou fugir, mas foi capturado por populares que iniciaram um linchamento. Os policiais intervieram e salvaram o homem, que estava com um mandado de pris\u00e3o em aberto.<\/p>\n<p>A Pol\u00edcia Militar apreendeu as armas usadas pelos assaltantes e encaminhou o preso para a delegacia. Nenhum policial ou civil ficou ferido na ocorr\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"Uma a\u00e7\u00e3o r\u00e1pida da Pol\u00edcia Militar impediu um assalto na Feira do Eldorado, em Contagem, na Regi\u00e3o Metropolitana de Belo Horizonte, na tarde desta sexta-feira (12 de janeiro de 2024). Dois homens armados tentaram roubar os comerciantes da feira, mas foram surpreendidos por uma viatura que fazia patrulhamento no bairro. Um dos assaltantes reagiu \u00e0 [&hellip;]","protected":false},"author":2,"featured_media":8212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[23,41,18,24],"class_list":["post-8210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-belo-horizonte-mg","tag-capa","tag-minas-gerais","tag-policia-militar"],"_links":{"self":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/8210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/comments?post=8210"}],"version-history":[{"count":2,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/8210\/revisions"}],"predecessor-version":[{"id":8225,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/posts\/8210\/revisions\/8225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media\/8212"}],"wp:attachment":[{"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/media?parent=8210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/categories?post=8210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticias-gospel.org\/teste\/wp-json\/wp\/v2\/tags?post=8210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}